{"id":2535,"date":"2025-10-17T09:44:34","date_gmt":"2025-10-17T07:44:34","guid":{"rendered":"https:\/\/storydox.de\/?p=2535"},"modified":"2025-10-27T18:24:12","modified_gmt":"2025-10-27T17:24:12","slug":"weiter-so-oder-anders-weiter-gedanken-zur-zukunft-der-wirtschaft","status":"publish","type":"post","link":"https:\/\/storydox.de\/en\/2025\/10\/17\/weiter-so-oder-anders-weiter-gedanken-zur-zukunft-der-wirtschaft\/","title":{"rendered":"Weiter so oder anders weiter? Gedanken zur Zukunft der Wirtschaft"},"content":{"rendered":"<p>Als Anfang Oktober zum 22. mal der <a href=\"https:\/\/www.ludwig-erhard-initiative.de\/fuerther-ludwig-erhard-preis\/preisverleihung-2025\/\">Ludwig-Erhard-Preis in F\u00fcrth<\/a> verliehen wurde, hatte das wording des Wegbereiters des Wirtschaftswunders mal wieder Hochkonjunktur. Oder was die Politik und die Propagandisten unter der sozialen Marktwirtschaft verstehen: Liberalisierung und Entb\u00fcrokratisierung, unternehmen und nicht vom Sozialstaat leben, etc. pp.<\/p>\r\n<h4>Wohlstand in Gefahr<\/h4>\r\n<p>In der Tat ist unser Wohlstand in Gefahr. Nicht nur, weil zu viele in der sozialen H\u00e4ngematte liegen, sondern auch und vor allem, weil wir das Wachstumspferd zu Tode geritten haben. Die von Deutschland in der Vergangenheit gro\u00df gemachten Industrien (der chemischen Grundstoffe, des klassisch-angetriebenen Premium-Automobils usw.) haben die Zukunft hinter sich, nachdem sie, also wir, ich nehme mich nicht aus, den Planeten gepl\u00fcndert haben.<\/p>\r\n<h4>Kosten des Wohlstands<\/h4>\r\n<p>Sicher k\u00f6nnen wir uns auf dieser Welt noch versorgen, doch unser Verbrauch hat inzwischen Dimensionen angenommen, der f\u00fcr Generationen Folgen hat. Zum Beispiel ist seit Beginn der Industrialisierung der CO\u2082-Gehalt der Erdatmosph\u00e4re um rund 50\u202f% gestiegen: von etwa 280\u202fppm (Teile pro Million) um 1750 auf 420\u2013425\u202fppm heute. Der Anstieg ist der Grund f\u00fcr Erderw\u00e4rmung, die sich nur unter gro\u00dfen Anstrengungen bremsen l\u00e4sst.<\/p>\r\n<h4>Ursachen des Wohlstands<\/h4>\r\n<p>Anstrengen mussten sich auch unsere Gro\u00dfv\u00e4ter und -m\u00fctter, als sie zum Wiederaufbau Deutschlands antraten. Ihr Flei\u00df f\u00fchrte zum sog. Wirtschaftswunder. Es war die Leistung Erhards, der CDU\/CSU und einiger Verb\u00e4nde Wirtschaft und Soziales zusammen zu denken und auf den Begriff zu bringen. Das Wohlstandsversprechen war so attraktiv und umsetzbar, dass dem Erfolgsrezept viele folgten und immer noch folgen wollen.<\/p>\r\n<h4>Zukunft des Wohlstands<\/h4>\r\n<p>Zeitgem\u00e4\u00df ist die Nachfolge nicht. Wir brauchen eine Modernisierung des Rezepts, das den ver\u00e4nderten Rahmenbedingungen, in erster Linie dem Klimawandel, Rechnung tr\u00e4gt und so weit wie m\u00f6glich Tribut zollt. Es war nicht nur ein politisches, sondern vor allem ein gesellschaftliches Versagen, dass die \u00f6kologisch-soziale Marktwirtschaft nicht fortgeschrieben wurde. Wir hatten die Wahl!<\/p>\r\n<h4>Erhard 2.0<\/h4>\r\n<p>Wohlstand f\u00fcr alle auf Kosten von anderen bzw. anderem ist ein Konzept des 20. Jahrhunderts. Wir m\u00fcssen das Wirtschaftliche endlich und unbedingt mit dem \u00d6kologischen zusammen denken. Wie es Ludwig Erhard getan h\u00e4tte. Gegen alle Widerst\u00e4nde, f\u00fcr eine bessere Zukunft.<\/p>","protected":false},"excerpt":{"rendered":"<p>Als Anfang Oktober zum 22. mal der Ludwig-Erhard-Preis in F\u00fcrth verliehen wurde, hatte das wording des Wegbereiters des Wirtschaftswunders mal wieder Hochkonjunktur. Oder was die Politik und die Propagandisten unter der sozialen Marktwirtschaft verstehen: Liberalisierung und Entb\u00fcrokratisierung, unternehmen und nicht vom Sozialstaat leben, etc. pp. Wohlstand in Gefahr In der Tat ist unser Wohlstand in [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2539,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-2535","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reflexion"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Weiter so oder anders weiter? Gedanken zur Zukunft der Wirtschaft - storydox.de<\/title>\n<meta name=\"description\" content=\"Die Soziale Marktwirtschaft brachte Wohlstand f\u00fcr alle auf Kosten der (Um)Welt. Wie Ludwig Erhard Wirtschaft und Soziales zusammen dachte, m\u00fcssen wir die Umwelt mitdenken.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/storydox.de\/en\/2025\/10\/17\/weiter-so-oder-anders-weiter-gedanken-zur-zukunft-der-wirtschaft\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Weiter so oder anders weiter? Gedanken zur Zukunft der Wirtschaft - storydox.de\" \/>\n<meta property=\"og:description\" content=\"Die Soziale Marktwirtschaft brachte Wohlstand f\u00fcr alle auf Kosten der (Um)Welt. Wie Ludwig Erhard Wirtschaft und Soziales zusammen dachte, m\u00fcssen wir die Umwelt mitdenken.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/storydox.de\/en\/2025\/10\/17\/weiter-so-oder-anders-weiter-gedanken-zur-zukunft-der-wirtschaft\/\" \/>\n<meta property=\"og:site_name\" content=\"storydox.de\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-17T07:44:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-27T17:24:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/storydox.de\/wp-content\/uploads\/2025\/10\/Ludwig-Erhard-Preis.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1585\" \/>\n\t<meta property=\"og:image:height\" content=\"2075\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dr. Claus W. Sch\u00e4fer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dr. Claus W. Sch\u00e4fer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/storydox.de\\\/2025\\\/10\\\/17\\\/weiter-so-oder-anders-weiter-gedanken-zur-zukunft-der-wirtschaft\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/storydox.de\\\/2025\\\/10\\\/17\\\/weiter-so-oder-anders-weiter-gedanken-zur-zukunft-der-wirtschaft\\\/\"},\"author\":{\"name\":\"Dr. Claus W. Sch\u00e4fer\",\"@id\":\"https:\\\/\\\/storydox.de\\\/#\\\/schema\\\/person\\\/433f383d05c76f80a500a0e6d9daa214\"},\"headline\":\"Weiter so oder anders weiter? Gedanken zur Zukunft der Wirtschaft\",\"datePublished\":\"2025-10-17T07:44:34+00:00\",\"dateModified\":\"2025-10-27T17:24:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/storydox.de\\\/2025\\\/10\\\/17\\\/weiter-so-oder-anders-weiter-gedanken-zur-zukunft-der-wirtschaft\\\/\"},\"wordCount\":368,\"image\":{\"@id\":\"https:\\\/\\\/storydox.de\\\/2025\\\/10\\\/17\\\/weiter-so-oder-anders-weiter-gedanken-zur-zukunft-der-wirtschaft\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/storydox.de\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Ludwig-Erhard-Preis.jpg\",\"articleSection\":[\"Reflexion\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/storydox.de\\\/2025\\\/10\\\/17\\\/weiter-so-oder-anders-weiter-gedanken-zur-zukunft-der-wirtschaft\\\/\",\"url\":\"https:\\\/\\\/storydox.de\\\/2025\\\/10\\\/17\\\/weiter-so-oder-anders-weiter-gedanken-zur-zukunft-der-wirtschaft\\\/\",\"name\":\"Weiter so oder anders weiter? Gedanken zur Zukunft der Wirtschaft - storydox.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/storydox.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/storydox.de\\\/2025\\\/10\\\/17\\\/weiter-so-oder-anders-weiter-gedanken-zur-zukunft-der-wirtschaft\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/storydox.de\\\/2025\\\/10\\\/17\\\/weiter-so-oder-anders-weiter-gedanken-zur-zukunft-der-wirtschaft\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/storydox.de\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Ludwig-Erhard-Preis.jpg\",\"datePublished\":\"2025-10-17T07:44:34+00:00\",\"dateModified\":\"2025-10-27T17:24:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/storydox.de\\\/#\\\/schema\\\/person\\\/433f383d05c76f80a500a0e6d9daa214\"},\"description\":\"Die Soziale Marktwirtschaft brachte Wohlstand f\u00fcr alle auf Kosten der (Um)Welt. Wie Ludwig Erhard Wirtschaft und Soziales zusammen dachte, m\u00fcssen wir die Umwelt mitdenken.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/storydox.de\\\/2025\\\/10\\\/17\\\/weiter-so-oder-anders-weiter-gedanken-zur-zukunft-der-wirtschaft\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/storydox.de\\\/2025\\\/10\\\/17\\\/weiter-so-oder-anders-weiter-gedanken-zur-zukunft-der-wirtschaft\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/storydox.de\\\/2025\\\/10\\\/17\\\/weiter-so-oder-anders-weiter-gedanken-zur-zukunft-der-wirtschaft\\\/#primaryimage\",\"url\":\"https:\\\/\\\/storydox.de\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Ludwig-Erhard-Preis.jpg\",\"contentUrl\":\"https:\\\/\\\/storydox.de\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Ludwig-Erhard-Preis.jpg\",\"width\":1585,\"height\":2075},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/storydox.de\\\/2025\\\/10\\\/17\\\/weiter-so-oder-anders-weiter-gedanken-zur-zukunft-der-wirtschaft\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/storydox.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Weiter so oder anders weiter? Gedanken zur Zukunft der Wirtschaft\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/storydox.de\\\/#website\",\"url\":\"https:\\\/\\\/storydox.de\\\/\",\"name\":\"storydox.de\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/storydox.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/storydox.de\\\/#\\\/schema\\\/person\\\/433f383d05c76f80a500a0e6d9daa214\",\"name\":\"Dr. Claus W. Sch\u00e4fer\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50f791b318b69223f42673538cd1744fb0ced553fa74e7bc2e07c496327607a2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50f791b318b69223f42673538cd1744fb0ced553fa74e7bc2e07c496327607a2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/50f791b318b69223f42673538cd1744fb0ced553fa74e7bc2e07c496327607a2?s=96&d=mm&r=g\",\"caption\":\"Dr. Claus W. Sch\u00e4fer\"},\"url\":\"https:\\\/\\\/storydox.de\\\/en\\\/author\\\/25f230af17980c9f\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Weiter so oder anders weiter? Gedanken zur Zukunft der Wirtschaft - storydox.de","description":"Die Soziale Marktwirtschaft brachte Wohlstand f\u00fcr alle auf Kosten der (Um)Welt. Wie Ludwig Erhard Wirtschaft und Soziales zusammen dachte, m\u00fcssen wir die Umwelt mitdenken.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/storydox.de\/en\/2025\/10\/17\/weiter-so-oder-anders-weiter-gedanken-zur-zukunft-der-wirtschaft\/","og_locale":"en_GB","og_type":"article","og_title":"Weiter so oder anders weiter? Gedanken zur Zukunft der Wirtschaft - storydox.de","og_description":"Die Soziale Marktwirtschaft brachte Wohlstand f\u00fcr alle auf Kosten der (Um)Welt. Wie Ludwig Erhard Wirtschaft und Soziales zusammen dachte, m\u00fcssen wir die Umwelt mitdenken.","og_url":"https:\/\/storydox.de\/en\/2025\/10\/17\/weiter-so-oder-anders-weiter-gedanken-zur-zukunft-der-wirtschaft\/","og_site_name":"storydox.de","article_published_time":"2025-10-17T07:44:34+00:00","article_modified_time":"2025-10-27T17:24:12+00:00","og_image":[{"width":1585,"height":2075,"url":"https:\/\/storydox.de\/wp-content\/uploads\/2025\/10\/Ludwig-Erhard-Preis.jpg","type":"image\/jpeg"}],"author":"Dr. Claus W. Sch\u00e4fer","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Dr. Claus W. Sch\u00e4fer","Estimated reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/storydox.de\/2025\/10\/17\/weiter-so-oder-anders-weiter-gedanken-zur-zukunft-der-wirtschaft\/#article","isPartOf":{"@id":"https:\/\/storydox.de\/2025\/10\/17\/weiter-so-oder-anders-weiter-gedanken-zur-zukunft-der-wirtschaft\/"},"author":{"name":"Dr. Claus W. Sch\u00e4fer","@id":"https:\/\/storydox.de\/#\/schema\/person\/433f383d05c76f80a500a0e6d9daa214"},"headline":"Weiter so oder anders weiter? Gedanken zur Zukunft der Wirtschaft","datePublished":"2025-10-17T07:44:34+00:00","dateModified":"2025-10-27T17:24:12+00:00","mainEntityOfPage":{"@id":"https:\/\/storydox.de\/2025\/10\/17\/weiter-so-oder-anders-weiter-gedanken-zur-zukunft-der-wirtschaft\/"},"wordCount":368,"image":{"@id":"https:\/\/storydox.de\/2025\/10\/17\/weiter-so-oder-anders-weiter-gedanken-zur-zukunft-der-wirtschaft\/#primaryimage"},"thumbnailUrl":"https:\/\/storydox.de\/wp-content\/uploads\/2025\/10\/Ludwig-Erhard-Preis.jpg","articleSection":["Reflexion"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/storydox.de\/2025\/10\/17\/weiter-so-oder-anders-weiter-gedanken-zur-zukunft-der-wirtschaft\/","url":"https:\/\/storydox.de\/2025\/10\/17\/weiter-so-oder-anders-weiter-gedanken-zur-zukunft-der-wirtschaft\/","name":"Weiter so oder anders weiter? Gedanken zur Zukunft der Wirtschaft - storydox.de","isPartOf":{"@id":"https:\/\/storydox.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/storydox.de\/2025\/10\/17\/weiter-so-oder-anders-weiter-gedanken-zur-zukunft-der-wirtschaft\/#primaryimage"},"image":{"@id":"https:\/\/storydox.de\/2025\/10\/17\/weiter-so-oder-anders-weiter-gedanken-zur-zukunft-der-wirtschaft\/#primaryimage"},"thumbnailUrl":"https:\/\/storydox.de\/wp-content\/uploads\/2025\/10\/Ludwig-Erhard-Preis.jpg","datePublished":"2025-10-17T07:44:34+00:00","dateModified":"2025-10-27T17:24:12+00:00","author":{"@id":"https:\/\/storydox.de\/#\/schema\/person\/433f383d05c76f80a500a0e6d9daa214"},"description":"Die Soziale Marktwirtschaft brachte Wohlstand f\u00fcr alle auf Kosten der (Um)Welt. Wie Ludwig Erhard Wirtschaft und Soziales zusammen dachte, m\u00fcssen wir die Umwelt mitdenken.","breadcrumb":{"@id":"https:\/\/storydox.de\/2025\/10\/17\/weiter-so-oder-anders-weiter-gedanken-zur-zukunft-der-wirtschaft\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/storydox.de\/2025\/10\/17\/weiter-so-oder-anders-weiter-gedanken-zur-zukunft-der-wirtschaft\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/storydox.de\/2025\/10\/17\/weiter-so-oder-anders-weiter-gedanken-zur-zukunft-der-wirtschaft\/#primaryimage","url":"https:\/\/storydox.de\/wp-content\/uploads\/2025\/10\/Ludwig-Erhard-Preis.jpg","contentUrl":"https:\/\/storydox.de\/wp-content\/uploads\/2025\/10\/Ludwig-Erhard-Preis.jpg","width":1585,"height":2075},{"@type":"BreadcrumbList","@id":"https:\/\/storydox.de\/2025\/10\/17\/weiter-so-oder-anders-weiter-gedanken-zur-zukunft-der-wirtschaft\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/storydox.de\/"},{"@type":"ListItem","position":2,"name":"Weiter so oder anders weiter? Gedanken zur Zukunft der Wirtschaft"}]},{"@type":"WebSite","@id":"https:\/\/storydox.de\/#website","url":"https:\/\/storydox.de\/","name":"storydox.de","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/storydox.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/storydox.de\/#\/schema\/person\/433f383d05c76f80a500a0e6d9daa214","name":"Dr. Claus W. Sch\u00e4fer","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/50f791b318b69223f42673538cd1744fb0ced553fa74e7bc2e07c496327607a2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/50f791b318b69223f42673538cd1744fb0ced553fa74e7bc2e07c496327607a2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/50f791b318b69223f42673538cd1744fb0ced553fa74e7bc2e07c496327607a2?s=96&d=mm&r=g","caption":"Dr. Claus W. Sch\u00e4fer"},"url":"https:\/\/storydox.de\/en\/author\/25f230af17980c9f\/"}]}},"views":41,"_links":{"self":[{"href":"https:\/\/storydox.de\/en\/wp-json\/wp\/v2\/posts\/2535","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/storydox.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/storydox.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/storydox.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/storydox.de\/en\/wp-json\/wp\/v2\/comments?post=2535"}],"version-history":[{"count":6,"href":"https:\/\/storydox.de\/en\/wp-json\/wp\/v2\/posts\/2535\/revisions"}],"predecessor-version":[{"id":2570,"href":"https:\/\/storydox.de\/en\/wp-json\/wp\/v2\/posts\/2535\/revisions\/2570"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/storydox.de\/en\/wp-json\/wp\/v2\/media\/2539"}],"wp:attachment":[{"href":"https:\/\/storydox.de\/en\/wp-json\/wp\/v2\/media?parent=2535"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/storydox.de\/en\/wp-json\/wp\/v2\/categories?post=2535"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/storydox.de\/en\/wp-json\/wp\/v2\/tags?post=2535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}